{"id":238,"count":4,"description":"","link":"https:\/\/www.branchenportal24.de\/sbbp24\/category\/marketing\/","name":"Marketing","slug":"marketing","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Marketing Archive - Socialblog Branchenportal24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.branchenportal24.de\/sbbp24\/category\/marketing\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:type\" content=\"article\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:title\" content=\"Marketing Archive - Socialblog Branchenportal24\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.branchenportal24.de\/sbbp24\/category\/marketing\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:site_name\" content=\"Socialblog Branchenportal24\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" class=\"yoast-seo-meta-tag\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.branchenportal24.de\\\/sbbp24\\\/category\\\/marketing\\\/\",\"url\":\"https:\\\/\\\/www.branchenportal24.de\\\/sbbp24\\\/category\\\/marketing\\\/\",\"name\":\"Marketing Archive - Socialblog Branchenportal24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.branchenportal24.de\\\/sbbp24\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.branchenportal24.de\\\/sbbp24\\\/category\\\/marketing\\\/#breadcrumb\"},\"inLanguage\":\"de\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.branchenportal24.de\\\/sbbp24\\\/category\\\/marketing\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.branchenportal24.de\\\/sbbp24\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Marketing\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.branchenportal24.de\\\/sbbp24\\\/#website\",\"url\":\"https:\\\/\\\/www.branchenportal24.de\\\/sbbp24\\\/\",\"name\":\"Socialblog Branchenportal24\",\"description\":\"Blog Anwaltsportal24 Rechtstipps und mehr\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.branchenportal24.de\\\/sbbp24\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Marketing Archive - Socialblog Branchenportal24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.branchenportal24.de\/sbbp24\/category\/marketing\/","og_locale":"de_DE","og_type":"article","og_title":"Marketing Archive - Socialblog Branchenportal24","og_url":"https:\/\/www.branchenportal24.de\/sbbp24\/category\/marketing\/","og_site_name":"Socialblog Branchenportal24","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.branchenportal24.de\/sbbp24\/category\/marketing\/","url":"https:\/\/www.branchenportal24.de\/sbbp24\/category\/marketing\/","name":"Marketing Archive - Socialblog Branchenportal24","isPartOf":{"@id":"https:\/\/www.branchenportal24.de\/sbbp24\/#website"},"breadcrumb":{"@id":"https:\/\/www.branchenportal24.de\/sbbp24\/category\/marketing\/#breadcrumb"},"inLanguage":"de"},{"@type":"BreadcrumbList","@id":"https:\/\/www.branchenportal24.de\/sbbp24\/category\/marketing\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.branchenportal24.de\/sbbp24\/"},{"@type":"ListItem","position":2,"name":"Marketing"}]},{"@type":"WebSite","@id":"https:\/\/www.branchenportal24.de\/sbbp24\/#website","url":"https:\/\/www.branchenportal24.de\/sbbp24\/","name":"Socialblog Branchenportal24","description":"Blog Anwaltsportal24 Rechtstipps und mehr","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.branchenportal24.de\/sbbp24\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/www.branchenportal24.de\/sbbp24\/wp-json\/wp\/v2\/categories\/238","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.branchenportal24.de\/sbbp24\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.branchenportal24.de\/sbbp24\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.branchenportal24.de\/sbbp24\/wp-json\/wp\/v2\/posts?categories=238"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}